{"id":10592,"date":"2023-10-18T20:32:06","date_gmt":"2023-10-18T20:32:06","guid":{"rendered":"https:\/\/betasite.metamap.com\/?p=10592"},"modified":"2024-07-18T15:03:33","modified_gmt":"2024-07-18T15:03:33","slug":"aml-2023-los-nuevos-retos-que-las-empresas-deberan-enfrentar","status":"publish","type":"post","link":"https:\/\/www.metamap.com\/es\/aml-2023-los-nuevos-retos-que-las-empresas-deberan-enfrentar\/","title":{"rendered":"AML 2023: Los Nuevos Retos que las Empresas deber\u00e1n enfrentar"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"10592\" class=\"elementor elementor-10592 elementor-2100\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4c4c4986 section-dark-bg e-flex e-con-boxed e-con e-parent\" data-id=\"4c4c4986\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3132a2d9 e-con-full e-flex e-con e-child\" data-id=\"3132a2d9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1f1bba29 elementor-hidden-desktop elementor-widget elementor-widget-html\" data-id=\"1f1bba29\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<button class=\"button-go-back\" onclick=\"history.back()\">< Regresar<\/button>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-51f7c273 elementor-hidden-tablet elementor-hidden-mobile section-dark-bg elementor-widget elementor-widget-breadcrumbs\" data-id=\"51f7c273\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"breadcrumbs\"><span><span><a href=\"https:\/\/www.metamap.com\/es\/\">Home<\/a><\/span><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-19c6823b elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"19c6823b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-438cc5fb elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"438cc5fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1 id=\"articleTitle\" class=\"article-title-white\">AML 2023: Los Nuevos Retos que las Empresas deber\u00e1n enfrentar\n<\/h1>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-598c930 elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"598c930\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>ON DEMAND WEBINAR\u00a0 \u00a0 \u00a0OCT 22, 2022\u00a0 \u00a0|\u00a0 56 MIN<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-32527c67 elementor-hidden-mobile elementor-widget elementor-widget-global elementor-global-1566 elementor-widget-text-editor\" data-id=\"32527c67\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<a id=\"btnEmail\" class=\"article-link-icon\" href=\"#\"><img decoding=\"async\" src=\"https:\/\/www.metamap.com\/ychochat\/2023\/10\/icon__share_email.png\" alt=\"\" width=\"24\" height=\"24\" \/><\/a>\n<a id=\"btnDownload\" class=\"article-link-icon\" href=\"#\"><img decoding=\"async\" src=\"https:\/\/www.metamap.com\/ychochat\/2023\/10\/icon__share_download-1.png\" alt=\"\" width=\"24\" \/><\/a>\n<a id=\"btnLinkedin\" class=\"article-link-icon\" href=\"#\"><img decoding=\"async\" src=\"https:\/\/www.metamap.com\/ychochat\/2024\/02\/linkedin_logo_s.png\" alt=\"\" width=\"24\"><\/a>\n<a id=\"btnTwitter\" class=\"article-link-icon\" href=\"#\"><img decoding=\"async\" src=\"https:\/\/www.metamap.com\/ychochat\/2023\/12\/footer-twitter.png\" alt=\"\" width=\"24\" \/><\/a>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-23348955 e-con-full e-flex e-con e-child\" data-id=\"23348955\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3f748a0d elementor-widget elementor-widget-html\" data-id=\"3f748a0d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<iframe width=\"100%\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/ipOoUYLpY-o?si=zTebjgQhAetzht8R\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2a120c9 elementor-hidden-desktop elementor-hidden-tablet section-dark-bg-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"2a120c9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-066b355 e-con-full e-flex e-con e-child\" data-id=\"066b355\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4f7818c elementor-widget elementor-widget-text-editor\" data-id=\"4f7818c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>OCT 22, 2022\u00a0 \u00a0|\u00a0 56 MIN<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f0700b7 e-con-full e-flex e-con e-child\" data-id=\"f0700b7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-322b7b1 elementor-widget elementor-widget-global elementor-global-1647 elementor-widget-text-editor\" data-id=\"322b7b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<a id=\"btnEmailMobile\" class=\"article-link-icon\" href=\"#\"><img decoding=\"async\" src=\"https:\/\/www.metamap.com\/ychochat\/2023\/10\/icon__share_email.png\" alt=\"\" width=\"24\" height=\"24\" \/><\/a>\n<a id=\"btnDownloadMobile\" class=\"article-link-icon\" href=\"#\"><img decoding=\"async\" src=\"https:\/\/www.metamap.com\/ychochat\/2023\/10\/icon__share_download-1.png\" alt=\"\" width=\"24\" \/><\/a>\n<a id=\"btnLinkedinMobile\" class=\"article-link-icon\" href=\"#\"><img decoding=\"async\" src=\"https:\/\/www.metamap.com\/ychochat\/2024\/02\/linkedin_logo_s.png\" alt=\"\" width=\"24\" \/><\/a>\n<a id=\"btnTwitterMobile\" class=\"article-link-icon\" href=\"#\"><img decoding=\"async\" src=\"https:\/\/www.metamap.com\/ychochat\/2023\/12\/footer-twitter.png\" alt=\"\" width=\"24\" \/><\/a>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0fbe681 elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"0fbe681\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3980278 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"3980278\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-38f539cf e-flex e-con-boxed e-con e-parent\" data-id=\"38f539cf\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7bb170bd e-con-full e-flex e-con e-child\" data-id=\"7bb170bd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-52afb2b6 elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"52afb2b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<span style=\"font-size: 11px; display: block; margin: 0 0 6px 0;\">ESCRITO POR\n<\/span>\n\n<a style=\"color: white;\" href=\"https:\/\/www.metamap.com\/about-metamap\/\">MetaMap<\/a>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3a9d6115 e-con-full e-flex e-con e-child\" data-id=\"3a9d6115\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-57687f00 hero-text elementor-widget elementor-widget-text-editor\" data-id=\"57687f00\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00bfSab\u00eda que, seg\u00fan el\u00a0<strong>Banco Interamericano de Desarrollo (BID)<\/strong>\u00a0se calcula que la cantidad de dinero procedente de la delincuencia y la corrupci\u00f3n que se\u00a0blanquea\u00a0en empresas ficticias representa cada a\u00f1o entre el 2% y el 5% del PIB mundial, es decir, entre 800.000 y 2 billones de d\u00f3lares?<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-110b0322 elementor-hidden-desktop elementor-hidden-tablet e-flex e-con-boxed e-con e-child\" data-id=\"110b0322\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7dd23170 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"7dd23170\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-583f4166 elementor-widget elementor-widget-text-editor\" data-id=\"583f4166\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<span style=\"font-size: 11px; display: block; margin: 0 0 6px 0;\">ESCRITO POR\n<\/span>\n\nMetaMap\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-15c33018 e-flex e-con-boxed e-con e-parent\" data-id=\"15c33018\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-59ef2b70 e-con-full article-nav-menu-container-ext   e-flex e-con e-child\" data-id=\"59ef2b70\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-72e7df84  article-nav-menu-container e-flex e-con-boxed e-con e-child\" data-id=\"72e7df84\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-482aa3f0 elementor-toc--minimized-on-mobile elementor-widget elementor-widget-table-of-contents\" data-id=\"482aa3f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;headings_by_tags&quot;:[&quot;h2&quot;],&quot;exclude_headings_by_selector&quot;:[],&quot;marker_view&quot;:&quot;bullets&quot;,&quot;icon&quot;:{&quot;value&quot;:&quot;&quot;,&quot;library&quot;:&quot;&quot;},&quot;minimized_on&quot;:&quot;mobile&quot;,&quot;no_headings_message&quot;:&quot;No se ha encontrado ning\\u00fan encabezado en esta p\\u00e1gina.&quot;,&quot;minimize_box&quot;:&quot;yes&quot;,&quot;min_height&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;min_height_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;min_height_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"table-of-contents.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-toc__header\">\n\t\t\t\t\t\t<h5 class=\"elementor-toc__header-title\">\n\t\t\t\tContents\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-toc__toggle-button elementor-toc__toggle-button--expand\" role=\"button\" tabindex=\"0\" aria-controls=\"elementor-toc__482aa3f0\" aria-expanded=\"true\" aria-label=\"Abrir la tabla de contenidos\"><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/div>\n\t\t\t\t<div class=\"elementor-toc__toggle-button elementor-toc__toggle-button--collapse\" role=\"button\" tabindex=\"0\" aria-controls=\"elementor-toc__482aa3f0\" aria-expanded=\"true\" aria-label=\"Cerrar la tabla de contenidos\"><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div id=\"elementor-toc__482aa3f0\" class=\"elementor-toc__body\">\n\t\t\t<div class=\"elementor-toc__spinner-container\">\n\t\t\t\t<i class=\"elementor-toc__spinner eicon-animation-spin eicon-loading\" aria-hidden=\"true\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2d41377a e-con-full e-flex e-con e-child\" data-id=\"2d41377a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-3f7f8ab e-con-full e-flex e-con e-child\" data-id=\"3f7f8ab\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-03064d8 elementor-widget__width-initial webinar-person-text elementor-widget elementor-widget-text-editor\" data-id=\"03064d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong><img decoding=\"async\" class=\"wp-image-2120 alignleft\" src=\"https:\/\/www.metamap.com\/ychochat\/2023\/10\/aml-2023-luis-mercado.png\" alt=\"\" width=\"75\" height=\"75\" srcset=\"https:\/\/www.metamap.com\/ychochat\/2023\/10\/aml-2023-luis-mercado.png 242w, https:\/\/www.metamap.com\/ychochat\/2023\/10\/aml-2023-luis-mercado-150x150.png 150w\" sizes=\"(max-width: 75px) 100vw, 75px\" \/>Luis Mercado<\/strong><br \/><span style=\"color: #808080;\">VP of Global Compliance for payment intermediaries<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7a6daa2 elementor-widget__width-initial webinar-person-text elementor-widget elementor-widget-text-editor\" data-id=\"7a6daa2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong><img decoding=\"async\" class=\"wp-image-2123 alignleft\" src=\"https:\/\/www.metamap.com\/ychochat\/2023\/10\/aml-2023-guillermo-mera.png\" alt=\"\" width=\"75\" height=\"75\" srcset=\"https:\/\/www.metamap.com\/ychochat\/2023\/10\/aml-2023-guillermo-mera.png 242w, https:\/\/www.metamap.com\/ychochat\/2023\/10\/aml-2023-guillermo-mera-150x150.png 150w\" sizes=\"(max-width: 75px) 100vw, 75px\" \/>Guillermo Mera<\/strong><br \/><span style=\"color: #808080;\">Account Executive at MetaMap<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba2130a elementor-widget__width-initial webinar-person-text elementor-widget elementor-widget-text-editor\" data-id=\"ba2130a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2126 alignleft\" src=\"https:\/\/www.metamap.com\/ychochat\/2023\/10\/aml-2023-laura-guerrero.png\" alt=\"\" width=\"75\" height=\"75\" srcset=\"https:\/\/www.metamap.com\/ychochat\/2023\/10\/aml-2023-laura-guerrero.png 242w, https:\/\/www.metamap.com\/ychochat\/2023\/10\/aml-2023-laura-guerrero-150x150.png 150w\" sizes=\"(max-width: 75px) 100vw, 75px\" \/>Laura Guerrero<\/strong><br \/><span style=\"color: #808080;\">Head of Events and Marketing<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-15cdfba elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"15cdfba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4371d3eb elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"4371d3eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00bfSab\u00eda que, seg\u00fan el\u00a0<a href=\"https:\/\/www.iadb.org\/en\/news\/keeping-eye-washing-machine\"><strong>Banco Interamericano de Desarrollo (BID)<\/strong><\/a>\u00a0se calcula que la cantidad de dinero procedente de la delincuencia y la corrupci\u00f3n que se\u00a0<a href=\"https:\/\/www.iadb.org\/en\/news\/keeping-eye-washing-machine\">blanquea\u00a0<\/a>en empresas ficticias representa cada a\u00f1o entre el 2% y el 5% del PIB mundial, es decir, entre 800.000 y 2 billones de d\u00f3lares?<\/p><p>En esta ocasi\u00f3n,\u00a0<strong>Laura Guerrero, Lider de Eventos y Marketing y Guillermo Mera, Ejecutivo de cuenta en MetaMap,<\/strong>\u00a0tuvieron el gusto de platicar con\u00a0<strong>Luis Mercado, especialista en banca, sobre el cumplimiento de la normativa contra el blanqueo de capitales.<\/strong><\/p><p>Conocido por sus siglas en ingl\u00e9s\u00a0<strong>AML (Anti Money Laundering)<\/strong>, esta normativa dicta los procedimientos que siguen las instituciones financieras para prevenir, detectar, responder y eliminar los riesgos inherentes y residuales del blanqueo de capitales, la financiaci\u00f3n del terrorismo y el fraude.<\/p><p>Como se podr\u00e1n imaginar, para los sectores financiero, fintech, bancario y de criptomonedas, cumplir con normas internacionales de lucha contra el blanqueo de capitales no es una opci\u00f3n, sino una obligaci\u00f3n legal.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bf84855 e-flex e-con-boxed e-con e-child\" data-id=\"bf84855\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cbfb22e elementor-widget elementor-widget-image\" data-id=\"cbfb22e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"40\" height=\"32\" src=\"https:\/\/www.metamap.com\/ychochat\/2023\/10\/quotation-marks_desk.png\" class=\"attachment-large size-large wp-image-1716\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-befe46a elementor-widget elementor-widget-text-editor\" data-id=\"befe46a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"quote-text\">&#8220;Creo firmemente que el impacto de las instituciones financieras en las comunidades es enorme. Sin embargo, hay delitos, como los financieros, entre ellos el blanqueo de capitales, que pueden da\u00f1ar fuertemente la contabilidad de estas instituciones y, en consecuencia, perjudicar tambi\u00e9n a la comunidad.&#8221;<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3bf5b40 elementor-widget elementor-widget-text-editor\" data-id=\"3bf5b40\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>\u2014Luis Mercado, especialista en banca.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-58211e33 elementor-widget elementor-widget-image\" data-id=\"58211e33\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"448\" src=\"https:\/\/www.metamap.com\/ychochat\/2023\/10\/aml-2023-challenges-1-1024x574.jpg\" class=\"attachment-large size-large wp-image-2145\" alt=\"\" srcset=\"https:\/\/www.metamap.com\/ychochat\/2023\/10\/aml-2023-challenges-1-1024x574.jpg 1024w, https:\/\/www.metamap.com\/ychochat\/2023\/10\/aml-2023-challenges-1-300x168.jpg 300w, https:\/\/www.metamap.com\/ychochat\/2023\/10\/aml-2023-challenges-1-768x430.jpg 768w, https:\/\/www.metamap.com\/ychochat\/2023\/10\/aml-2023-challenges-1-1536x860.jpg 1536w, https:\/\/www.metamap.com\/ychochat\/2023\/10\/aml-2023-challenges-1.jpg 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-44339a63 elementor-widget elementor-widget-text-editor\" data-id=\"44339a63\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"what\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><strong>Siguiendo el dinero<\/strong><\/h2><p>Dada la cantidad de corrupci\u00f3n, grupos criminales y ganacias de procedencias il\u00edcitas, lo que buscan las normativas AML es prevenir que este dinero entre en el sistema financiero leg\u00edtimo, ya sea a traves de bancos, fintechs o empresas.<\/p><p>Luis ha escuchado personas que creen que estas normativas son algun tipo de \u201ctrampa\u201d para que el gobierno pueda vigilar las ganacias de las personas. Este no es el caso, AML no solo sirve para detener a criminales o politicos corruptos, sino tambi\u00e9n para proteger a los consumidores.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-eb25c93 e-flex e-con-boxed e-con e-child\" data-id=\"eb25c93\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-216afa5 elementor-widget elementor-widget-image\" data-id=\"216afa5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"40\" height=\"32\" src=\"https:\/\/www.metamap.com\/ychochat\/2023\/10\/quotation-marks_desk.png\" class=\"attachment-large size-large wp-image-1716\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-962222b elementor-widget elementor-widget-text-editor\" data-id=\"962222b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"quote-text\">&#8220;Cada vez oigo m\u00e1s opiniones en las que la gente piensa que los gobiernos o las instituciones internacionales buscan tener controles de prevenci\u00f3n del blanqueo de dinero como una forma de cobrar impuestos a la gente. Parece que los bancos quieren saber cu\u00e1nto ganas para dec\u00edrselo al Estado y cobrar impuestos, pero eso est\u00e1 muy lejos de la realidad.&#8221;<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c842bd elementor-widget elementor-widget-text-editor\" data-id=\"5c842bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>\u2014Luis Mercado, especialista en banca.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9aedf1f elementor-widget elementor-widget-text-editor\" data-id=\"9aedf1f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Las normativas buscan definir cu\u00e1ndo un dinero leg\u00edtimo se vuelve ileg\u00edtimo. Por ejemplo, si una empresa roba dinero de sus inversionistas o clientes, este dinero inmediatamente se vuelve dinero sucio.<\/p><p>Cuando el dinero ileg\u00edtimo se puede mezclar en el sistema financiero sin limites, se pierde cualquier oportunidad de proteger a las comunidades y frenar el avance de la corrupci\u00f3n, el abuso y el crimen.<\/p><h3><strong>La tecnolog\u00eda es un aliado, \u00bfpero para qui\u00e9n?<\/strong><\/h3><p>El avance tecnol\u00f3gico en el manejo de dinero, tanto para depositar c\u00f3mo para retirar fondos le ha dado un nuevo nivel de comfort, facilidad e inclusi\u00f3n a los usuarios de servicios financieros. Sin embargo, las mismas caracteristicas que le facilitan la vida al ciudadano com\u00fan, le dan nuevas armas al pol\u00edtico corrupto o al crimen organizado.<\/p><p>Muchas instituciones financieras o empresas han desarrollado controles en la tecnolog\u00eda para evitar que el dinero ileg\u00edtimo tenga acceso a sus organizaciones y al mercado financiero. Estos mismo controles suelen ser tan estrictos que a veces bloquean oportunidades para miles de personas.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-31606b0 e-flex e-con-boxed e-con e-child\" data-id=\"31606b0\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-244be3e elementor-widget elementor-widget-image\" data-id=\"244be3e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"40\" height=\"32\" src=\"https:\/\/www.metamap.com\/ychochat\/2023\/10\/quotation-marks_desk.png\" class=\"attachment-large size-large wp-image-1716\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8ff06d3 elementor-widget elementor-widget-text-editor\" data-id=\"8ff06d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"quote-text\">&#8220;Las grandes entidades quieren entender c\u00f3mo esta tecnolog\u00eda puede permitir o mejorar la experiencia de usuario, hemos visto grandes inversiones de grandes bancos en fintechs que las han convertido en unicornios, pero al mismo tiempo, quieren tener cuidado con aquellos negocios que pueden ser utilizados para especular o dirigir fondos de origen il\u00edcito.&#8221;<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-61b10d9 elementor-widget elementor-widget-text-editor\" data-id=\"61b10d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>\u2014Luis Mercado, especialista en banca.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5428151 elementor-widget elementor-widget-text-editor\" data-id=\"5428151\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Las instituciones se ven forzadas a protegerse mientras limitan las oportunidades a clientes leg\u00edtimos que no pueden alcanzar los altos est\u00e1ndares.<\/p><h3><strong>C\u00f3mo tu empresa puede enfrentar AML<\/strong><\/h3><p>La tecnolog\u00eda puede ayudar a las empresas a reducir ese espacio de desconfianza que el fraude, el delito, y la corrupci\u00f3n han creado entre ellas y sus clientes. Los sistemas biom\u00e9tricos que ayudan a verificar la identidad de los usuarios son solo alguna de las formas en las que las instituciones pueden fortalecer sus controles y al mismo tiempo crear inclusividad en el mercado.<\/p><p>Las empresas deben empezar a concentrar sus esfuerzos en:<\/p><ul role=\"list\"><li><strong>Cumplimiento:\u00a0<\/strong>Asegur\u00e1ndose de siempre estar al tanto de las legislaciones e implementar los cambios necesarios.<\/li><li><strong>Tecnolog\u00eda:\u00a0<\/strong>Pensar en la tecnolog\u00eda como un aliado y no como algo a lo que se le debe temer o incluso rechazar.<\/li><li><strong>Seguridad:<\/strong>\u00a0Implementer procesos que protejan a los clientes y a la empresa.<\/li><li><strong>Finanzas:<\/strong>\u00a0Un departamento de finanzas s\u00f3lido garantiza la capacidad para identificar posible fraude o lavado de dinero.\u00a0<\/li><\/ul><p>De acuerdo con Guillermo, las empresas deben de aprender a ser<strong><em>\u00a0&#8220;resilientes&#8221;.<\/em><\/strong>\u00a0Esto quiere decir que no pueden dejar que las legislaciones y los cambios te frenen de buscar siempre adaptarte. En este mismo tono, Luis cree que\u00a0<strong><em>&#8220;la creatividad es clave&#8221;<\/em><\/strong>\u00a0para las empresas que quieren sobrevivir en el futuro pero no siempre tienen grandes recursos.<\/p><p>Guillermo y Laura hablaron de c\u00f3mo MetaMap est\u00e1 ayudando a las empresas con tecnolog\u00eda que les permite verificar a sus clientes mientras mantienen el cumplimiento de todas las normas, incluyendo AML<\/p><p>A traves de sistemas para validar la identidad como biometricos y verificaci\u00f3n de documentos, MetaMap le da la posibilidad a las empresas de quitarse la carga sobre el cumplimiento de normativas.<\/p><p>MetaMap ofrece tecnolog\u00edas con un alto nivel de seguridad que les permiten a las empresas ofrecer m\u00e1s oportunidades a los clientes de forma segura. Guillermo cree que el rol de MetaMap es clave ya que\u00a0<strong><em>&#8220;toda la responsabilidad de cumplimiento la asuma MetaMap y no el cliente&#8221;.<\/em><\/strong><\/p><p>Para conocer m\u00e1s sobre c\u00f3mo MetaMap puede ayudar a tu empresa a defenderse de actos il\u00edcitos y as\u00ed proteger a sus clientes, no dudes en\u00a0<a href=\"https:\/\/www.metamap.com\/get-free-product-trial\">cont\u00e1ctarnos<\/a>\u00a0hoy mismo y unos de nuestros expertos responder\u00e1 a todas tus preguntas.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-96e152e e-flex e-con-boxed e-con e-parent\" data-id=\"96e152e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3bd2876 e-con-full e-flex e-con e-child\" data-id=\"3bd2876\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2aa2b0f e-con-full e-flex e-con e-child\" data-id=\"2aa2b0f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a4c0376 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"a4c0376\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c05f54 elementor-widget elementor-widget-global elementor-global-16938 elementor-widget-text-editor\" data-id=\"2c05f54\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<a id=\"btnEmailBottom\" class=\"article-link-icon\" href=\"#\"><img decoding=\"async\" src=\"https:\/\/www.metamap.com\/ychochat\/2023\/10\/icon__share_email.png\" alt=\"\" width=\"24\" height=\"24\" \/><\/a>\n<a id=\"btnDownloadBottom\" class=\"article-link-icon\" href=\"#\"><img decoding=\"async\" src=\"https:\/\/www.metamap.com\/ychochat\/2023\/10\/icon__share_download-1.png\" alt=\"\" width=\"24\" \/><\/a>\n<a id=\"btnLinkedinBottom\" class=\"article-link-icon\" href=\"#\"><img decoding=\"async\" src=\"https:\/\/www.metamap.com\/ychochat\/2024\/02\/linkedin_logo_s.png\" alt=\"\" width=\"24\" \/><\/a>\n<a id=\"btnTwitterBottom\" class=\"article-link-icon\" href=\"#\"><img decoding=\"async\" src=\"https:\/\/www.metamap.com\/ychochat\/2023\/12\/footer-twitter.png\" alt=\"\" width=\"24\" \/><\/a>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f0e69e2 e-flex e-con-boxed e-con e-parent\" data-id=\"f0e69e2\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0eb459e elementor-widget elementor-widget-global elementor-global-1627 elementor-widget-html\" data-id=\"0eb459e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<script>\n\n    let emailBtn = document.getElementById(\"btnEmail\");\n    \n    let emailBtn2 = document.getElementById(\"btnEmailBottom\");\n    \n    let emailBtnMobile = document.getElementById(\"btnEmailMobile\");\n    \n    let downloadBtn = document.getElementById(\"btnDownload\");\n    \n    let downloadBtn2 = document.getElementById(\"btnDownloadBottom\");\n    \n    let downloadBtnMobile = document.getElementById(\"btnDownloadMobile\");\n    \n    let linkedinBtn = document.getElementById(\"btnLinkedin\");\n    \n    let linkedinBtn2 = document.getElementById(\"btnLinkedinBottom\");\n    \n    let linkedinBtnMobile = document.getElementById(\"btnLinkedinMobile\");\n    \n    let twitterBtn = document.getElementById(\"btnTwitter\");\n    \n     let twitterBtn2 = document.getElementById(\"btnTwitterBottom\");\n     \n     let twitterBtnMobile = document.getElementById(\"btnTwitterMobile\");\n    \n    let articleTitle = document.getElementsByTagName(\"title\")[0].innerHTML;\n    \n    const currentUrl = window.location.href\n    \n    \n    function sendEmailDefault(){\n  var email = \"name@domain.com\";\n  var subject = \"Take a look at this MetaMap article\";\n  var msgBody = \"Hi! take a look at this MetaMap article \" + articleTitle + \" at \" +\n  currentUrl;\n  window.open(`mailto:${email}?subject=${subject}&body=${msgBody}`);\n}\n    \n    downloadBtn.onclick= function(){\n        window.print()\n    }\n    \n     downloadBtn2.onclick= function(){\n        window.print()\n    }\n    \n     downloadBtnMobile.onclick= function(){\n        window.print()\n    }\n    \n    \n    emailBtn.onclick= function(){\n        sendEmailDefault()\n    }\n    \n    emailBtn2.onclick= function(){\n        sendEmailDefault()\n    }\n    \n     emailBtnMobile.onclick= function(){\n        sendEmailDefault()\n    }\n    \n    \n    linkedinBtn.onclick= function(){\n        window.open('http:\/\/www.linkedin.com\/shareArticle?mini=true&url='+encodeURIComponent(currentUrl), '', 'left=0,top=0,width=250,height=530,personalbar=0,toolbar=0,scrollbars=0,resizable=0');\n    }\n    \n        linkedinBtn2.onclick= function(){\n        window.open('http:\/\/www.linkedin.com\/shareArticle?mini=true&url='+encodeURIComponent(currentUrl), '', 'left=0,top=0,width=250,height=530,personalbar=0,toolbar=0,scrollbars=0,resizable=0');\n    }\n    \n       linkedinBtnMobile.onclick= function(){\n        window.open('http:\/\/www.linkedin.com\/shareArticle?mini=true&url='+encodeURIComponent(currentUrl), '', 'left=0,top=0,width=250,height=530,personalbar=0,toolbar=0,scrollbars=0,resizable=0');\n    }\n    \n    twitterBtn.onclick= function(){\n        window.open( 'https:\/\/twitter.com\/share?text='+articleTitle+'&url='+encodeURIComponent(currentUrl), '', 'left=0,top=0,width=290,height=430,personalbar=0,toolbar=0,scrollbars=0,resizable=0');\n    }\n    \n        twitterBtn2.onclick= function(){\n        window.open( 'https:\/\/twitter.com\/share?text='+articleTitle+'&url='+encodeURIComponent(currentUrl), '', 'left=0,top=0,width=290,height=430,personalbar=0,toolbar=0,scrollbars=0,resizable=0');\n    }\n   \n    twitterBtnMobile.onclick= function(){\n        window.open( 'https:\/\/twitter.com\/share?text='+articleTitle+'&url='+encodeURIComponent(currentUrl), '', 'left=0,top=0,width=290,height=430,personalbar=0,toolbar=0,scrollbars=0,resizable=0');\n    } \n\n\n    \n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-55fb0f5 elementor-widget elementor-widget-text-editor\" data-id=\"55fb0f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>Contenido Relacionado<\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ed0e1f6 elementor-pagination-type-bullets elementor-pagination-position-outside elementor-widget elementor-widget-loop-carousel\" data-id=\"ed0e1f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;template_id&quot;:16974,&quot;_skin&quot;:&quot;post&quot;,&quot;slides_to_show&quot;:&quot;3&quot;,&quot;slides_to_show_tablet&quot;:&quot;2&quot;,&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;edit_handle_selector&quot;:&quot;.elementor-loop-container&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;offset_sides&quot;:&quot;none&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"loop-carousel.post\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"swiper elementor-loop-container elementor-grid\" role=\"list\" dir=\"ltr\">\n\t\t\t\t<div class=\"swiper-wrapper\" aria-live=\"off\">\n\t\t<style id=\"loop-16974\">.elementor-16974 .elementor-element.elementor-element-eeec26c{--display:flex;--flex-direction:row;--container-widget-width:initial;--container-widget-height:100%;--container-widget-flex-grow:1;--container-widget-align-self:stretch;--flex-wrap-mobile:wrap;--padding-top:0px;--padding-bottom:0px;--padding-left:0px;--padding-right:0px;}.elementor-16974 .elementor-element.elementor-element-6e248e6{--display:flex;--padding-top:0px;--padding-bottom:0px;--padding-left:0px;--padding-right:0px;}.elementor-widget-theme-post-featured-image .widget-image-caption{color:var( --e-global-color-text );}.elementor-16974 .elementor-element.elementor-element-faff55d{--display:flex;--margin-top:0px;--margin-bottom:0px;--margin-left:-15px;--margin-right:0px;}.elementor-widget-post-info .elementor-icon-list-item:not(:last-child):after{border-color:var( --e-global-color-text );}.elementor-widget-post-info .elementor-icon-list-icon i{color:var( --e-global-color-primary );}.elementor-widget-post-info .elementor-icon-list-icon svg{fill:var( --e-global-color-primary );}.elementor-widget-post-info .elementor-icon-list-text, .elementor-widget-post-info .elementor-icon-list-text a{color:var( --e-global-color-secondary );}.elementor-16974 .elementor-element.elementor-element-4999654 .elementor-icon-list-icon{width:14px;}.elementor-16974 .elementor-element.elementor-element-4999654 .elementor-icon-list-icon i{font-size:14px;}.elementor-16974 .elementor-element.elementor-element-4999654 .elementor-icon-list-icon svg{--e-icon-list-icon-size:14px;}.elementor-16974 .elementor-element.elementor-element-4999654 .elementor-icon-list-text, .elementor-16974 .elementor-element.elementor-element-4999654 .elementor-icon-list-text a{color:#292A2A;}.elementor-16974 .elementor-element.elementor-element-4999654 .elementor-icon-list-item{font-size:11px;}.elementor-widget-heading .elementor-heading-title{color:var( --e-global-color-primary );}.elementor-16974 .elementor-element.elementor-element-84ffb4c .elementor-heading-title{font-size:18px;font-weight:400;line-height:22px;color:#000000;}<\/style>\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"16974\" class=\"elementor elementor-16974 swiper-slide e-loop-item e-loop-item-10636 post-10636 post type-post status-publish format-standard has-post-thumbnail hentry category-finteches category-recursos category-transporte category-webinar-recursos\" data-elementor-post-type=\"elementor_library\" role=\"group\" aria-roledescription=\"slide\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-eeec26c e-flex e-con-boxed e-con e-parent\" data-id=\"eeec26c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6e248e6 e-flex e-con-boxed e-con e-child\" data-id=\"6e248e6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e809016 elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"e809016\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.metamap.com\/es\/como-mejorar-el-seguimiento-de-las-transacciones-a-traves-de-la-inteligencia-artificial\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"729\" height=\"1024\" src=\"https:\/\/www.metamap.com\/ychochat\/2023\/10\/ai-efficiency-due-diligence-webinar-729x1024.png\" class=\"attachment-large size-large wp-image-17706\" alt=\"\" srcset=\"https:\/\/www.metamap.com\/ychochat\/2023\/10\/ai-efficiency-due-diligence-webinar-729x1024.png 729w, https:\/\/www.metamap.com\/ychochat\/2023\/10\/ai-efficiency-due-diligence-webinar-214x300.png 214w, https:\/\/www.metamap.com\/ychochat\/2023\/10\/ai-efficiency-due-diligence-webinar-768x1078.png 768w, https:\/\/www.metamap.com\/ychochat\/2023\/10\/ai-efficiency-due-diligence-webinar.png 832w\" sizes=\"(max-width: 729px) 100vw, 729px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-faff55d e-flex e-con-boxed e-con e-child\" data-id=\"faff55d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4999654 elementor-widget elementor-widget-post-info\" data-id=\"4999654\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"post-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-inline-items elementor-icon-list-items elementor-post-info\">\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-561c02c elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-custom\">\n\t\t\t\t\t\t\t\t\t\tWEBINAR |\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-255620b elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-custom\">\n\t\t\t\t\t\t\t\t\t\t54 MIN\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-84ffb4c elementor-widget elementor-widget-heading\" data-id=\"84ffb4c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.metamap.com\/es\/como-mejorar-el-seguimiento-de-las-transacciones-a-traves-de-la-inteligencia-artificial\/\">C\u00f3mo mejorar el seguimiento de las transacciones a trav\u00e9s de la IA<\/a><\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"16974\" class=\"elementor elementor-16974 swiper-slide e-loop-item e-loop-item-10631 post-10631 post type-post status-publish format-standard has-post-thumbnail hentry category-prestamos category-recursos category-webinar-recursos\" data-elementor-post-type=\"elementor_library\" role=\"group\" aria-roledescription=\"slide\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-eeec26c e-flex e-con-boxed e-con e-parent\" data-id=\"eeec26c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6e248e6 e-flex e-con-boxed e-con e-child\" data-id=\"6e248e6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e809016 elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"e809016\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.metamap.com\/es\/pagos-digitales-en-el-2024-tres-desafios-de-seguridad\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"729\" height=\"1024\" src=\"https:\/\/www.metamap.com\/ychochat\/2023\/10\/digital-payments-challenges-webinar-729x1024.png\" class=\"attachment-large size-large wp-image-17694\" alt=\"\" srcset=\"https:\/\/www.metamap.com\/ychochat\/2023\/10\/digital-payments-challenges-webinar-729x1024.png 729w, https:\/\/www.metamap.com\/ychochat\/2023\/10\/digital-payments-challenges-webinar-214x300.png 214w, https:\/\/www.metamap.com\/ychochat\/2023\/10\/digital-payments-challenges-webinar-768x1078.png 768w, https:\/\/www.metamap.com\/ychochat\/2023\/10\/digital-payments-challenges-webinar.png 832w\" sizes=\"(max-width: 729px) 100vw, 729px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-faff55d e-flex e-con-boxed e-con e-child\" data-id=\"faff55d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4999654 elementor-widget elementor-widget-post-info\" data-id=\"4999654\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"post-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-inline-items elementor-icon-list-items elementor-post-info\">\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-561c02c elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-custom\">\n\t\t\t\t\t\t\t\t\t\tWEBINAR |\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-255620b elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-custom\">\n\t\t\t\t\t\t\t\t\t\t48 MIN\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-84ffb4c elementor-widget elementor-widget-heading\" data-id=\"84ffb4c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.metamap.com\/es\/pagos-digitales-en-el-2024-tres-desafios-de-seguridad\/\">Pagos digitales en el 2024: tres desaf\u00edos de seguridad<\/a><\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"16974\" class=\"elementor elementor-16974 swiper-slide e-loop-item e-loop-item-10623 post-10623 post type-post status-publish format-standard has-post-thumbnail hentry category-banca category-recursos category-webinar-recursos\" data-elementor-post-type=\"elementor_library\" role=\"group\" aria-roledescription=\"slide\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-eeec26c e-flex e-con-boxed e-con e-parent\" data-id=\"eeec26c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6e248e6 e-flex e-con-boxed e-con e-child\" data-id=\"6e248e6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e809016 elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"e809016\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.metamap.com\/es\/el-futuro-de-la-banca-la-proxima-transformacion-digital\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"729\" height=\"1024\" src=\"https:\/\/www.metamap.com\/ychochat\/2023\/10\/digital-transformation-banking-webinar-729x1024.png\" class=\"attachment-large size-large wp-image-17681\" alt=\"\" srcset=\"https:\/\/www.metamap.com\/ychochat\/2023\/10\/digital-transformation-banking-webinar-729x1024.png 729w, https:\/\/www.metamap.com\/ychochat\/2023\/10\/digital-transformation-banking-webinar-214x300.png 214w, https:\/\/www.metamap.com\/ychochat\/2023\/10\/digital-transformation-banking-webinar-768x1078.png 768w, https:\/\/www.metamap.com\/ychochat\/2023\/10\/digital-transformation-banking-webinar.png 832w\" sizes=\"(max-width: 729px) 100vw, 729px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-faff55d e-flex e-con-boxed e-con e-child\" data-id=\"faff55d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4999654 elementor-widget elementor-widget-post-info\" data-id=\"4999654\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"post-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-inline-items elementor-icon-list-items elementor-post-info\">\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-561c02c elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-custom\">\n\t\t\t\t\t\t\t\t\t\tWEBINAR |\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-255620b elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-custom\">\n\t\t\t\t\t\t\t\t\t\t56 MIN\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-84ffb4c elementor-widget elementor-widget-heading\" data-id=\"84ffb4c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.metamap.com\/es\/el-futuro-de-la-banca-la-proxima-transformacion-digital\/\">El futuro de la banca: la pr\u00f3xima transformaci\u00f3n digital<\/a><\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fbc0e4a e-flex e-con-boxed e-con e-parent\" data-id=\"fbc0e4a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ab70b80 e-con-full e-flex e-con e-child\" data-id=\"ab70b80\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-de60839 e-con-full e-flex e-con e-child\" data-id=\"de60839\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e33feb8 elementor-widget elementor-widget-text-editor\" data-id=\"e33feb8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<strong>Subscribase al newsletter y este al d\u00eda de nuestras noticias, promociones y ofertas. <\/strong>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a97a5f elementor-widget elementor-widget-global elementor-global-26405 elementor-widget-html\" data-id=\"1a97a5f\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"resources-form\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<script charset=\"utf-8\" type=\"text\/javascript\" src=\"\/\/js.hsforms.net\/forms\/embed\/v2.js\"><\/script>\n<script>\n  hbspt.forms.create({\n    region: \"na1\",\n    portalId: \"44602883\",\n    formId: \"9871a187-1fe5-4522-a2aa-75d5a88ab767\"\n  });\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-048915b e-con-full e-flex e-con e-child\" data-id=\"048915b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u00bfSab\u00eda que, seg\u00fan el Banco Interamericano de Desarrollo (BID) se calcula que la cantidad de dinero procedente de la delincuencia y la corrupci\u00f3n que se blanquea en empresas ficticias representa cada a\u00f1o entre el 2% y el 5% del PIB mundial, es decir, entre 800.000 y 2 billones de d\u00f3lares?<\/p>\n","protected":false},"author":1,"featured_media":17629,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[36,39],"tags":[],"class_list":["post-10592","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-recursos","category-webinar-recursos"],"yoast_head":"\n<title>AML 2023: Los Nuevos Retos que las Empresas deber\u00e1n enfrentar &#8226; MetaMap<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.metamap.com\/es\/aml-2023-los-nuevos-retos-que-las-empresas-deberan-enfrentar\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AML 2023: Los Nuevos Retos que las Empresas deber\u00e1n enfrentar\" \/>\n<meta property=\"og:description\" content=\"\u00bfSab\u00eda que, seg\u00fan el Banco Interamericano de Desarrollo (BID) se calcula que la cantidad de dinero procedente de la delincuencia y la corrupci\u00f3n que se blanquea en empresas ficticias representa cada a\u00f1o entre el 2% y el 5% del PIB mundial, es decir, entre 800.000 y 2 billones de d\u00f3lares?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.metamap.com\/es\/aml-2023-los-nuevos-retos-que-las-empresas-deberan-enfrentar\/\" \/>\n<meta property=\"og:site_name\" content=\"MetaMap\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/getmetamap\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-18T20:32:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-18T15:03:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.metamap.com\/ychochat\/2023\/10\/aml-2023-company-challenges-webinar.png\" \/>\n\t<meta property=\"og:image:width\" content=\"832\" \/>\n\t<meta property=\"og:image:height\" content=\"1168\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"MetaMap\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@getmetamap\" \/>\n<meta name=\"twitter:site\" content=\"@getmetamap\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"MetaMap\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"14 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.metamap.com\\\/es\\\/aml-2023-los-nuevos-retos-que-las-empresas-deberan-enfrentar\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.metamap.com\\\/es\\\/aml-2023-los-nuevos-retos-que-las-empresas-deberan-enfrentar\\\/\"},\"author\":{\"name\":\"MetaMap\",\"@id\":\"https:\\\/\\\/www.metamap.com\\\/es\\\/#\\\/schema\\\/person\\\/e91aaaf40c01577600869ddf7e230b95\"},\"headline\":\"AML 2023: Los Nuevos Retos que las Empresas deber\u00e1n enfrentar\",\"datePublished\":\"2023-10-18T20:32:06+00:00\",\"dateModified\":\"2024-07-18T15:03:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.metamap.com\\\/es\\\/aml-2023-los-nuevos-retos-que-las-empresas-deberan-enfrentar\\\/\"},\"wordCount\":1141,\"publisher\":{\"@id\":\"https:\\\/\\\/www.metamap.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.metamap.com\\\/es\\\/aml-2023-los-nuevos-retos-que-las-empresas-deberan-enfrentar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.metamap.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/aml-2023-company-challenges-webinar.png\",\"articleSection\":[\"Recursos\",\"Webinar\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.metamap.com\\\/es\\\/aml-2023-los-nuevos-retos-que-las-empresas-deberan-enfrentar\\\/\",\"url\":\"https:\\\/\\\/www.metamap.com\\\/es\\\/aml-2023-los-nuevos-retos-que-las-empresas-deberan-enfrentar\\\/\",\"name\":\"AML 2023: Los Nuevos Retos que las Empresas deber\u00e1n enfrentar &#8226; MetaMap\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.metamap.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.metamap.com\\\/es\\\/aml-2023-los-nuevos-retos-que-las-empresas-deberan-enfrentar\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.metamap.com\\\/es\\\/aml-2023-los-nuevos-retos-que-las-empresas-deberan-enfrentar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.metamap.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/aml-2023-company-challenges-webinar.png\",\"datePublished\":\"2023-10-18T20:32:06+00:00\",\"dateModified\":\"2024-07-18T15:03:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.metamap.com\\\/es\\\/aml-2023-los-nuevos-retos-que-las-empresas-deberan-enfrentar\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.metamap.com\\\/es\\\/aml-2023-los-nuevos-retos-que-las-empresas-deberan-enfrentar\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.metamap.com\\\/es\\\/aml-2023-los-nuevos-retos-que-las-empresas-deberan-enfrentar\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.metamap.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/aml-2023-company-challenges-webinar.png\",\"contentUrl\":\"https:\\\/\\\/www.metamap.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/aml-2023-company-challenges-webinar.png\",\"width\":832,\"height\":1168},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.metamap.com\\\/es\\\/aml-2023-los-nuevos-retos-que-las-empresas-deberan-enfrentar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.metamap.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Resources\",\"item\":\"https:\\\/\\\/www.metamap.com\\\/category\\\/resources\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Webinar\",\"item\":\"https:\\\/\\\/www.metamap.com\\\/category\\\/resources\\\/webinar\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"AML 2023: Los Nuevos Retos que las Empresas deber\u00e1n enfrentar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.metamap.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.metamap.com\\\/es\\\/\",\"name\":\"MetaMap\",\"description\":\"Identity Verification Platform for Global Companies\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.metamap.com\\\/es\\\/#organization\"},\"alternateName\":\"Metamap\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.metamap.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.metamap.com\\\/es\\\/#organization\",\"name\":\"Metamap\",\"url\":\"https:\\\/\\\/www.metamap.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.metamap.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.metamap.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/press_asset_logo-metamap.png\",\"contentUrl\":\"https:\\\/\\\/www.metamap.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/press_asset_logo-metamap.png\",\"width\":404,\"height\":252,\"caption\":\"Metamap\"},\"image\":{\"@id\":\"https:\\\/\\\/www.metamap.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/getmetamap\\\/\",\"https:\\\/\\\/x.com\\\/getmetamap\",\"https:\\\/\\\/www.instagram.com\\\/getmetamap\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/metmap\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.metamap.com\\\/es\\\/#\\\/schema\\\/person\\\/e91aaaf40c01577600869ddf7e230b95\",\"name\":\"MetaMap\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cf01239bd0e605d96c158027c9e0ae87f4132e804f3c49801398e971ebffb207?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cf01239bd0e605d96c158027c9e0ae87f4132e804f3c49801398e971ebffb207?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cf01239bd0e605d96c158027c9e0ae87f4132e804f3c49801398e971ebffb207?s=96&d=mm&r=g\",\"caption\":\"MetaMap\"},\"sameAs\":[\"https:\\\/\\\/www.metamap.com\"],\"url\":\"https:\\\/\\\/www.metamap.com\\\/es\\\/author\\\/metaus889\\\/\"}]}<\/script>\n","yoast_head_json":{"title":"AML 2023: Los Nuevos Retos que las Empresas deber\u00e1n enfrentar &#8226; MetaMap","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.metamap.com\/es\/aml-2023-los-nuevos-retos-que-las-empresas-deberan-enfrentar\/","og_locale":"es_ES","og_type":"article","og_title":"AML 2023: Los Nuevos Retos que las Empresas deber\u00e1n enfrentar","og_description":"\u00bfSab\u00eda que, seg\u00fan el Banco Interamericano de Desarrollo (BID) se calcula que la cantidad de dinero procedente de la delincuencia y la corrupci\u00f3n que se blanquea en empresas ficticias representa cada a\u00f1o entre el 2% y el 5% del PIB mundial, es decir, entre 800.000 y 2 billones de d\u00f3lares?","og_url":"https:\/\/www.metamap.com\/es\/aml-2023-los-nuevos-retos-que-las-empresas-deberan-enfrentar\/","og_site_name":"MetaMap","article_publisher":"https:\/\/www.facebook.com\/getmetamap\/","article_published_time":"2023-10-18T20:32:06+00:00","article_modified_time":"2024-07-18T15:03:33+00:00","og_image":[{"width":832,"height":1168,"url":"https:\/\/www.metamap.com\/ychochat\/2023\/10\/aml-2023-company-challenges-webinar.png","type":"image\/png"}],"author":"MetaMap","twitter_card":"summary_large_image","twitter_creator":"@getmetamap","twitter_site":"@getmetamap","twitter_misc":{"Escrito por":"MetaMap","Tiempo de lectura":"14 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.metamap.com\/es\/aml-2023-los-nuevos-retos-que-las-empresas-deberan-enfrentar\/#article","isPartOf":{"@id":"https:\/\/www.metamap.com\/es\/aml-2023-los-nuevos-retos-que-las-empresas-deberan-enfrentar\/"},"author":{"name":"MetaMap","@id":"https:\/\/www.metamap.com\/es\/#\/schema\/person\/e91aaaf40c01577600869ddf7e230b95"},"headline":"AML 2023: Los Nuevos Retos que las Empresas deber\u00e1n enfrentar","datePublished":"2023-10-18T20:32:06+00:00","dateModified":"2024-07-18T15:03:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.metamap.com\/es\/aml-2023-los-nuevos-retos-que-las-empresas-deberan-enfrentar\/"},"wordCount":1141,"publisher":{"@id":"https:\/\/www.metamap.com\/es\/#organization"},"image":{"@id":"https:\/\/www.metamap.com\/es\/aml-2023-los-nuevos-retos-que-las-empresas-deberan-enfrentar\/#primaryimage"},"thumbnailUrl":"https:\/\/www.metamap.com\/ychochat\/2023\/10\/aml-2023-company-challenges-webinar.png","articleSection":["Recursos","Webinar"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.metamap.com\/es\/aml-2023-los-nuevos-retos-que-las-empresas-deberan-enfrentar\/","url":"https:\/\/www.metamap.com\/es\/aml-2023-los-nuevos-retos-que-las-empresas-deberan-enfrentar\/","name":"AML 2023: Los Nuevos Retos que las Empresas deber\u00e1n enfrentar &#8226; MetaMap","isPartOf":{"@id":"https:\/\/www.metamap.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.metamap.com\/es\/aml-2023-los-nuevos-retos-que-las-empresas-deberan-enfrentar\/#primaryimage"},"image":{"@id":"https:\/\/www.metamap.com\/es\/aml-2023-los-nuevos-retos-que-las-empresas-deberan-enfrentar\/#primaryimage"},"thumbnailUrl":"https:\/\/www.metamap.com\/ychochat\/2023\/10\/aml-2023-company-challenges-webinar.png","datePublished":"2023-10-18T20:32:06+00:00","dateModified":"2024-07-18T15:03:33+00:00","breadcrumb":{"@id":"https:\/\/www.metamap.com\/es\/aml-2023-los-nuevos-retos-que-las-empresas-deberan-enfrentar\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.metamap.com\/es\/aml-2023-los-nuevos-retos-que-las-empresas-deberan-enfrentar\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.metamap.com\/es\/aml-2023-los-nuevos-retos-que-las-empresas-deberan-enfrentar\/#primaryimage","url":"https:\/\/www.metamap.com\/ychochat\/2023\/10\/aml-2023-company-challenges-webinar.png","contentUrl":"https:\/\/www.metamap.com\/ychochat\/2023\/10\/aml-2023-company-challenges-webinar.png","width":832,"height":1168},{"@type":"BreadcrumbList","@id":"https:\/\/www.metamap.com\/es\/aml-2023-los-nuevos-retos-que-las-empresas-deberan-enfrentar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.metamap.com\/es\/"},{"@type":"ListItem","position":2,"name":"Resources","item":"https:\/\/www.metamap.com\/category\/resources\/"},{"@type":"ListItem","position":3,"name":"Webinar","item":"https:\/\/www.metamap.com\/category\/resources\/webinar\/"},{"@type":"ListItem","position":4,"name":"AML 2023: Los Nuevos Retos que las Empresas deber\u00e1n enfrentar"}]},{"@type":"WebSite","@id":"https:\/\/www.metamap.com\/es\/#website","url":"https:\/\/www.metamap.com\/es\/","name":"MetaMap","description":"Identity Verification Platform for Global Companies","publisher":{"@id":"https:\/\/www.metamap.com\/es\/#organization"},"alternateName":"Metamap","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.metamap.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.metamap.com\/es\/#organization","name":"Metamap","url":"https:\/\/www.metamap.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.metamap.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.metamap.com\/ychochat\/2023\/12\/press_asset_logo-metamap.png","contentUrl":"https:\/\/www.metamap.com\/ychochat\/2023\/12\/press_asset_logo-metamap.png","width":404,"height":252,"caption":"Metamap"},"image":{"@id":"https:\/\/www.metamap.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/getmetamap\/","https:\/\/x.com\/getmetamap","https:\/\/www.instagram.com\/getmetamap\/","https:\/\/www.linkedin.com\/company\/metmap"]},{"@type":"Person","@id":"https:\/\/www.metamap.com\/es\/#\/schema\/person\/e91aaaf40c01577600869ddf7e230b95","name":"MetaMap","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/cf01239bd0e605d96c158027c9e0ae87f4132e804f3c49801398e971ebffb207?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cf01239bd0e605d96c158027c9e0ae87f4132e804f3c49801398e971ebffb207?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cf01239bd0e605d96c158027c9e0ae87f4132e804f3c49801398e971ebffb207?s=96&d=mm&r=g","caption":"MetaMap"},"sameAs":["https:\/\/www.metamap.com"],"url":"https:\/\/www.metamap.com\/es\/author\/metaus889\/"}]}},"_links":{"self":[{"href":"https:\/\/www.metamap.com\/es\/wp-json\/wp\/v2\/posts\/10592","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.metamap.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.metamap.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.metamap.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.metamap.com\/es\/wp-json\/wp\/v2\/comments?post=10592"}],"version-history":[{"count":14,"href":"https:\/\/www.metamap.com\/es\/wp-json\/wp\/v2\/posts\/10592\/revisions"}],"predecessor-version":[{"id":26440,"href":"https:\/\/www.metamap.com\/es\/wp-json\/wp\/v2\/posts\/10592\/revisions\/26440"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.metamap.com\/es\/wp-json\/wp\/v2\/media\/17629"}],"wp:attachment":[{"href":"https:\/\/www.metamap.com\/es\/wp-json\/wp\/v2\/media?parent=10592"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.metamap.com\/es\/wp-json\/wp\/v2\/categories?post=10592"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.metamap.com\/es\/wp-json\/wp\/v2\/tags?post=10592"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}